{"id":23,"date":"2024-04-20T07:33:13","date_gmt":"2024-04-20T07:33:13","guid":{"rendered":"https:\/\/jdxt.honeyplaybox.eu\/?page_id=23"},"modified":"2024-07-04T08:34:06","modified_gmt":"2024-07-04T08:34:06","slug":"homepage","status":"publish","type":"page","link":"https:\/\/www.szunioncargo.com\/es\/","title":{"rendered":"Homepage"},"content":{"rendered":"<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:100vh\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-20 has-background-dim\"><\/span><video class=\"wp-block-cover__video-background intrinsic-ignore\" autoplay muted loop playsinline src=\"https:\/\/img.honeyplaybox.eu\/video\/szunioncargo-video.mp4\" data-object-fit=\"cover\"><\/video><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n\n<p class=\"has-text-align-center has-white-color has-text-color has-max-60-font-size\" style=\"font-style:normal;font-weight:900;line-height:1.2\"><strong>Create. Amaze. Inspire.<\/strong><\/p>\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-medium-font-size\">Inspiro is a Portfolio &amp; Photography WordPress Theme. This area supports self-hosted videos as well as videos from YouTube and Vimeo.<\/p>\n\n\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-white-color has-text-color wp-element-button\" href=\"https:\/\/www.szunioncargo.com\/es\/about\/\" style=\"border-radius:0px\">Learn More<\/a><\/div>\n\n<\/div>\n\n<\/div><\/div>\n\n\n\n<style>\n    .fuwuxm {\n        width: 100%;\n    }\n    .fuwuxm .servicebox {\n        width: 100%;\n        padding-bottom: 70px;\n        background-color: #fff;\n        margin: 30px auto 0;\n    }\n    .fuwuxm .servicebox .ser-text {\n        text-align: center;\n    }\n    .fuwuxm .servicebox .ser-tab {\n        display: flex;\n        justify-content: center;\n        align-items: center;\n        flex-wrap: wrap;\n        margin: 0 auto;\n        width: 1600px;\n    }\n    .fuwuxm .servicebox .ser-tab .item-tab {\n        margin: 8px 15px;\n        padding: 0 10px;\n        width: 20%;\n    }\n    .fuwuxm .servicebox .ser-tab .item-tab .c-hub-tile {\n        margin-bottom: 10px;\n        margin-left: -10px;\n        margin-right: -10px;\n    }\n    .fuwuxm .servicebox .ser-tab .item-tab .c-hub-tile a {\n        display: block;\n        position: relative;\n        box-sizing: content-box;\n        overflow: hidden;\n        color: #fff;\n        background-color: #000;\n        height: 300px;\n    }\n    .fuwuxm .c-hub-tile a img {\n        width: 100%;\n        height: 100%;\n        filter: none;\n        opacity: 1;\n        object-fit: cover;\n        transition: filter 0.2s ease-out, opacity 0.2s ease-out;\n    }\n    .fuwuxm .c-hub-tile a .caption {\n        position: absolute;\n        top: 50%;\n        left: 50%;\n        transform: translate(-50%, -50%);\n        text-align: center;\n        padding: 0 15px;\n        font-size: 32px;\n        width: 100%;\n    }\n\n    .fuwuxm .c-hub-tile a:before {\n        border: 5px solid transparent;\n        width: 100%;\n        height: 100%;\n        position: absolute;\n        z-index: 1000;\n        transition: border 0.2s ease-out;\n    }\n    .fuwuxm .c-hub-tile a:hover:before {\n        border: 5px solid #003f74;\n        transition: border 0.5s ease-out;\n    }\n    .fuwuxm .c-hub-tile a:after, .fuwuxm .c-hub-tile a:before {\n        content: ' ';\n        display: table;\n    }\n    .fuwuxm .c-hub-tile a .caption h4 {\n        color: #fff;\n        position: relative;\n        font-size: 38px;\n    }\n    .fuwuxm .c-hub-tile a .caption h4:after {\n        position: absolute;\n        width: 125px;\n        height: 30px;\n    }\n    .fuwuxm .c-hub-tile a:hover img {\n        filter: grayscale(100%) contrast(140%);\n        opacity: 0.4;\n        transition: filter 0.5s ease-out, opacity 0.5s ease-out;\n    }\n\n<\/style>\n<section class=\"fuwuxm\">\n    <div class=\"servicebox\">\n        <h2 class=\"ser-text\">Servicios<\/h2>\n        <!--                <div class=\"ser-text\">We deliver wherever you are<\/div>-->\n        <div class=\"ser-tab\">\n            <div class=\"item-tab\">\n                <div class=\"guideJump c-hub-tile\">\n                    <a href=\"https:\/\/www.szunioncargo.com\/es\/service-hy\/\">\n                        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/05\/hy-1.webp\" alt=\"\">\n                        <div class=\"caption\">\n                            <h4>Operaciones mar\u00edtimas<\/h4>\n                            <!-- <p>\u6211\u4eec\u81f4\u529b\u4e8e\u63a8\u52a8\u4e2d\u56fd\u7269\u6d41\u670d\u52a1\u4e1a\u7684\u5feb\u901f\u5168\u9762\u53d1\u5c55\uff0c\u5229\u7528\u5148\u8fdb\u7684\u7269\u6d41IT\u7cfb\u7edf\u5145\u5206\u6574\u5408\u8d44\u6e90\uff0c\u4e3a\u5ba2\u6237\u63d0\u4f9b\u5168\u65b9\u4f4d\u7269\u6d41\u53ca\u589e\u503c\u670d\u52a1<\/p> -->\n                        <\/div>\n                    <\/a>\n                <\/div>\n            <\/div>\n            <div class=\"item-tab\">\n                <div class=\"guideJump c-hub-tile\">\n                    <a href=\"https:\/\/www.szunioncargo.com\/es\/service-ky\/\">\n                        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/05\/ky-2.webp\" alt=\"\">\n                        <div class=\"caption\">\n                            <h4>Operaciones de transporte a\u00e9reo<\/h4>\n                            <!-- <p>\u6211\u4eec\u81f4\u529b\u4e8e\u63a8\u52a8\u4e2d\u56fd\u7269\u6d41\u670d\u52a1\u4e1a\u7684\u5feb\u901f\u5168\u9762\u53d1\u5c55\uff0c\u5229\u7528\u5148\u8fdb\u7684\u7269\u6d41IT\u7cfb\u7edf\u5145\u5206\u6574\u5408\u8d44\u6e90\uff0c\u4e3a\u5ba2\u6237\u63d0\u4f9b\u5168\u65b9\u4f4d\u7269\u6d41\u53ca\u589e\u503c\u670d\u52a1<\/p> -->\n                        <\/div>\n                    <\/a>\n                <\/div>\n            <\/div>\n            <div class=\"item-tab\">\n                <div class=\"guideJump c-hub-tile\">\n                    <a href=\"https:\/\/www.szunioncargo.com\/es\/service-ly\/\">\n                        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/ly-4.webp\" alt=\"\">\n                        <div class=\"caption\">\n                            <h4>Operaciones de transporte terrestre<\/h4>\n                            <!-- <p>\u6211\u4eec\u81f4\u529b\u4e8e\u63a8\u52a8\u4e2d\u56fd\u7269\u6d41\u670d\u52a1\u4e1a\u7684\u5feb\u901f\u5168\u9762\u53d1\u5c55\uff0c\u5229\u7528\u5148\u8fdb\u7684\u7269\u6d41IT\u7cfb\u7edf\u5145\u5206\u6574\u5408\u8d44\u6e90\uff0c\u4e3a\u5ba2\u6237\u63d0\u4f9b\u5168\u65b9\u4f4d\u7269\u6d41\u53ca\u589e\u503c\u670d\u52a1<\/p> -->\n                        <\/div>\n                    <\/a>\n                <\/div>\n            <\/div>\n            <div class=\"item-tab\">\n                <div class=\"guideJump c-hub-tile\">\n                    <a href=\"https:\/\/www.szunioncargo.com\/es\/service-kjds\/\">\n                        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/kjds.webp\" alt=\"\">\n                        <div class=\"caption\">\n                            <h4>Log\u00edstica de Comercio Electr\u00f3nico Transfronterizo<\/h4>\n                            <!-- <p>\u6211\u4eec\u81f4\u529b\u4e8e\u63a8\u52a8\u4e2d\u56fd\u7269\u6d41\u670d\u52a1\u4e1a\u7684\u5feb\u901f\u5168\u9762\u53d1\u5c55\uff0c\u5229\u7528\u5148\u8fdb\u7684\u7269\u6d41IT\u7cfb\u7edf\u5145\u5206\u6574\u5408\u8d44\u6e90\uff0c\u4e3a\u5ba2\u6237\u63d0\u4f9b\u5168\u65b9\u4f4d\u7269\u6d41\u53ca\u589e\u503c\u670d\u52a1<\/p> -->\n                        <\/div>\n                    <\/a>\n                <\/div>\n            <\/div>\n            <div class=\"item-tab\">\n                <div class=\"guideJump c-hub-tile\">\n                    <a href=\"https:\/\/www.szunioncargo.com\/es\/service-wxp\/\">\n                        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/05\/wxp-1.webp\" alt=\"\">\n                        <div class=\"caption\">\n                            <h4>Transporte de contenedores especializados<\/h4>\n                            <!-- <p>\u6211\u4eec\u81f4\u529b\u4e8e\u63a8\u52a8\u4e2d\u56fd\u7269\u6d41\u670d\u52a1\u4e1a\u7684\u5feb\u901f\u5168\u9762\u53d1\u5c55\uff0c\u5229\u7528\u5148\u8fdb\u7684\u7269\u6d41IT\u7cfb\u7edf\u5145\u5206\u6574\u5408\u8d44\u6e90\uff0c\u4e3a\u5ba2\u6237\u63d0\u4f9b\u5168\u65b9\u4f4d\u7269\u6d41\u53ca\u589e\u503c\u670d\u52a1<\/p> -->\n                        <\/div>\n                    <\/a>\n                <\/div>\n            <\/div>\n            <div class=\"item-tab\">\n                <div class=\"guideJump c-hub-tile\">\n                    <a href=\"https:\/\/www.szunioncargo.com\/es\/service-mdg\/\">\n                        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/05\/mdgfw.webp\" alt=\"\">\n                        <div class=\"caption\">\n                            <h4>Servicios en el Puerto de Destino<\/h4>\n                            <!-- <p>\u6211\u4eec\u81f4\u529b\u4e8e\u63a8\u52a8\u4e2d\u56fd\u7269\u6d41\u670d\u52a1\u4e1a\u7684\u5feb\u901f\u5168\u9762\u53d1\u5c55\uff0c\u5229\u7528\u5148\u8fdb\u7684\u7269\u6d41IT\u7cfb\u7edf\u5145\u5206\u6574\u5408\u8d44\u6e90\uff0c\u4e3a\u5ba2\u6237\u63d0\u4f9b\u5168\u65b9\u4f4d\u7269\u6d41\u53ca\u589e\u503c\u670d\u52a1<\/p> -->\n                        <\/div>\n                    <\/a>\n                <\/div>\n            <\/div>\n            <div class=\"item-tab\">\n                <div class=\"guideJump c-hub-tile\">\n                    <a href=\"https:\/\/www.szunioncargo.com\/es\/service-bgbj\/\">\n                        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/05\/bg.webp\" alt=\"\">\n                        <div class=\"caption\">\n                            <h4>Declaraci\u00f3n y Inspecci\u00f3n Aduanera<\/h4>\n                            <!-- <p>\u6211\u4eec\u81f4\u529b\u4e8e\u63a8\u52a8\u4e2d\u56fd\u7269\u6d41\u670d\u52a1\u4e1a\u7684\u5feb\u901f\u5168\u9762\u53d1\u5c55\uff0c\u5229\u7528\u5148\u8fdb\u7684\u7269\u6d41IT\u7cfb\u7edf\u5145\u5206\u6574\u5408\u8d44\u6e90\uff0c\u4e3a\u5ba2\u6237\u63d0\u4f9b\u5168\u65b9\u4f4d\u7269\u6d41\u53ca\u589e\u503c\u670d\u52a1<\/p> -->\n                        <\/div>\n                    <\/a>\n                <\/div>\n            <\/div>\n            <div class=\"item-tab\">\n                <div class=\"guideJump c-hub-tile\">\n                    <a href=\"https:\/\/www.szunioncargo.com\/es\/service-cc\/\">\n                        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/05\/ccfw.webp\" alt=\"\">\n                        <div class=\"caption\">\n                            <h4>Servicios de Almacenamiento<\/h4>\n                            <!-- <p>\u6211\u4eec\u81f4\u529b\u4e8e\u63a8\u52a8\u4e2d\u56fd\u7269\u6d41\u670d\u52a1\u4e1a\u7684\u5feb\u901f\u5168\u9762\u53d1\u5c55\uff0c\u5229\u7528\u5148\u8fdb\u7684\u7269\u6d41IT\u7cfb\u7edf\u5145\u5206\u6574\u5408\u8d44\u6e90\uff0c\u4e3a\u5ba2\u6237\u63d0\u4f9b\u5168\u65b9\u4f4d\u7269\u6d41\u53ca\u589e\u503c\u670d\u52a1<\/p> -->\n                        <\/div>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<link rel=\"preload\" as=\"image\" href=\"\/wp-content\/uploads\/2024\/05\/1691477778057.webp\">\n<style>\n            * {\n                margin: 0;\n                padding: 0;\n            }\n            .index-global p {\n                margin-bottom: 0;\n            }\n            .index-global, .index-global .gl_bk {\n                position: relative;\n            }\n            .index-global .gl_ab {\n                z-index: 1;\n                width: 100%;\n                position: absolute;\n                top: 1rem;\n            }\n            .w1720 {\n                padding: 0 90px;\n            }\n            .index-global .gl_ab .w34 {\n                width: 34%;\n            }\n            .index-global .gl_ab .w34 .pu_title {\n                color: #fff;\n                display: none;\n            }\n            .f48 {\n                font-size: 48px;\n                line-height: 1;\n            }\n            .index-global .gl_ab .w34 .gl_tog {\n                margin-top: 210px;\n                display: grid;\n                gap: 38px 0;\n            }\n            .index-global .gl_ab .w34 .gl_tog div {\n                cursor: pointer;\n                position: relative;\n            }\n            .ac {\n                -webkit-box-align: center;\n                -webkit-align-items: center;\n                -ms-flex-align: center;\n                align-items: center;\n            }\n            .df {\n                display: -webkit-box;\n                display: -webkit-flex;\n                display: -ms-flexbox;\n                display: flex;\n                -webkit-flex-wrap: wrap;\n                -ms-flex-wrap: wrap;\n                flex-wrap: wrap;\n            }\n            .f22 {\n                font-size: 22px;\n            }\n            .index-global .gl_ab .w34 .gl_tog div p {\n                transition: .4s;\n                color: #ffffffb3;\n                line-height: 1;\n                margin-left: 28px;\n            }\n            .index-global .gl_ab .w34 .gl_tog div.active p {\n                color: #fff;\n                font-size: 28px;\n            }\n            .index-global .gl_ab .w34 .gl_tog div {\n                cursor: pointer;\n                position: relative;\n            }\n            .index-global .gl_ab .w34 .gl_tog div.active i {\n                opacity: 1;\n            }\n            .index-global .gl_ab .w34 .gl_tog div i {\n                transition: .4s;\n                opacity: 0;\n                position: absolute;\n                left: 0;\n                top: 0;\n                display: block;\n                width: 6px;\n                height: 100%;\n                background: #009fdf;\n                transform: skew(-15deg);\n            }\n        <\/style>\n        <section class=\"index-global\">\n            <div class=\"gl_ab w1720\">\n                <div class=\"w34\">\n                    <div class=\"pu_title f48\">\u805a\u7126\u4e9a\u6d32\uff0c\u901a\u8fbe\u5168\u7403<\/div>\n                    <div class=\"gl_tog\">\n                        <!----><!---->\n                        <div class=\"df ac active\" data-id=\"lm\">\n                            <i><\/i>\n                            <p class=\"f22\">Am\u00e9rica Latina<\/p>\n                        <\/div>\n                        <div class=\"df ac\" data-id=\"yz\">\n                            <i><\/i>\n                            <p class=\"f22\">Asia<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"gl_bk\">\n                <picture>\n                    <source media=\"(max-width: 799px)\" srcset=\"\/wp-content\/uploads\/2024\/05\/lamei.webp\">\n                    <source media=\"(min-width: 800px)\" srcset=\"\/wp-content\/uploads\/2024\/05\/lamei.webp\">\n                    <img decoding=\"async\" alt=\"\" src=\"\/wp-content\/uploads\/2024\/05\/lamei.webp\">\n                <\/picture>\n            <\/div>\n            <div class=\"gl_point\">\n                <div class=\"yazhou\" data_title=\"\u6b27\u6d32\" style=\"\">\n                    <div class=\"round d1\"><\/div>\n                    <div class=\"round d2\"><\/div>\n                    <div class=\"round d3\"><\/div>\n                    <div class=\"round d4\"><\/div>\n                    <div class=\"round d5\"><\/div>\n                    <div class=\"round d6\"><\/div>\n                    <div class=\"round d7\"><\/div>\n                    <div class=\"round d8\"><\/div>\n                    <div class=\"round d9\"><\/div>\n                    <div class=\"round d10\"><\/div>\n                    <div class=\"round d11\"><\/div>\n                    <div class=\"round d12\"><\/div>\n                <\/div>\n                <div class=\"ouzhou\" data_title=\"\u6b27\u6d32\" style=\"display: none;\"><\/div>\n                <div class=\"feizhou\" data_title=\"\u975e\u6d32\" style=\"display: none;\"><\/div>\n                <div class=\"meizhou\" data_title=\"\u7f8e\u6d32\" style=\"display: none;\"><\/div>\n            <\/div>\n            <script>\n                const html_map = {\n                    'yz': `<picture><source media=\"(max-width: 799px)\" srcset=\"\/wp-content\/uploads\/2024\/04\/1691120786707.jpg\">\n                    <source media=\"(min-width: 800px)\" srcset=\"\/wp-content\/uploads\/2024\/05\/1691477778057.webp\">\n                    <img decoding=\"async\" alt=\"\" src=\"\/wp-content\/uploads\/2024\/05\/1691477778057.webp\"><\/picture>`,\n                    'lm': `<picture>\n                    <source media=\"(max-width: 799px)\" srcset=\"\/wp-content\/uploads\/2024\/05\/lamei.webp\">\n                    <source media=\"(min-width: 800px)\" srcset=\"\/wp-content\/uploads\/2024\/05\/lamei.webp\">\n                    <img decoding=\"async\" alt=\"\" src=\"\/wp-content\/uploads\/2024\/05\/lamei.webp\">\n                <\/picture>`\n                }\n                jQuery('.index-global .df').on('click', function(){\n                    let changeid = jQuery(this).data('id');\n                    let html = html_map[changeid];\n                    jQuery('.index-global .df').removeClass('active');\n                    jQuery(this).addClass('active');\n                    jQuery('.index-global .gl_bk').html(html);\n                });\n            <\/script>\n        <\/section>\n\n\n\n<style>\n    .index-partner {\n        padding: 0 12.5vw 6.5729vw;\n    }\n    .partner-title {\n        text-align: center;\n        margin-bottom: 40px;\n        margin-top: 30px;\n    }\n<\/style>\n<section class=\"index-partner\">\n    <h2 class=\"partner-title\">Socios<\/h2>\n    <div class=\"swiper mySwiper\">\n        <div class=\"swiper-wrapper\">\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-1.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-2.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-3.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-4.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-5.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-6.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-7.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-8.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-9.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-10.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-11.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-12.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-13.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-14.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-15.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-16.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-17.png\">\n            <\/div>\n            <div class=\"swiper-slide\">\n                <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/04\/partner-18.png\">\n            <\/div>\n        <\/div>\n        <div class=\"swiper-button-next\"><\/div>\n        <div class=\"swiper-button-prev\"><\/div>\n    <\/div>\n<\/section>\n<script src=\"https:\/\/cdn.jsdelivr.net\/npm\/swiper@11\/swiper-bundle.min.js\"><\/script>\n<script>\n    var swiper = new Swiper(\".mySwiper\", {\n        autoplay: {\n            delay: 1300,\n            disableOnInteraction: false,\n        },\n        loop: true,\n        \/\/ slidesPerView: 3,\n        \/\/ spaceBetween: 20,\n        breakpoints: {\n            768: {\n                slidesPerView: 6,\n                spaceBetween: 84,\n            },\n        },\n        \/* pagination: {\n          el: '.partner-pagination',\n          clickable: true,\n        }, *\/\n        navigation: {\n            nextEl: '.swiper-button-next',\n            prevEl: '.swiper-button-prev',\n        },\n    });\n<\/script>","protected":false},"excerpt":{"rendered":"<p>\u670d\u52a1\u9879\u76ee \u6d77\u8fd0\u4e1a\u52a1 \u7a7a\u8fd0\u4e1a\u52a1 \u9646\u8fd0\u4e1a\u52a1 \u8de8\u5883\u7535\u5546\u7269\u6d41 \u7279\u79cd\u67dc\u8fd0\u8f93 \u76ee\u7684\u6e2f\u670d\u52a1 \u62a5\u5173\u62a5\u68c0 \u4ed3\u50a8\u670d\u52a1 \u805a\u7126\u4e9a\u6d32\uff0c\u901a &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.szunioncargo.com\/es\/\" class=\"more-link\">Leer m\u00e1s<span class=\"screen-reader-text\"> \u00abHomepage\u00bb<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/homepage-no-hero.php","meta":{"footnotes":""},"class_list":["post-23","page","type-page","status-publish","hentry"],"featured_media_urls":[],"_links":{"self":[{"href":"https:\/\/www.szunioncargo.com\/es\/wp-json\/wp\/v2\/pages\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.szunioncargo.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.szunioncargo.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.szunioncargo.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.szunioncargo.com\/es\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":49,"href":"https:\/\/www.szunioncargo.com\/es\/wp-json\/wp\/v2\/pages\/23\/revisions"}],"predecessor-version":[{"id":1305,"href":"https:\/\/www.szunioncargo.com\/es\/wp-json\/wp\/v2\/pages\/23\/revisions\/1305"}],"wp:attachment":[{"href":"https:\/\/www.szunioncargo.com\/es\/wp-json\/wp\/v2\/media?parent=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}